{"id":3782,"date":"2024-12-03T14:29:29","date_gmt":"2024-12-03T13:29:29","guid":{"rendered":"https:\/\/www.maximus-resort.cz\/online-booking\/"},"modified":"2025-10-23T08:07:25","modified_gmt":"2025-10-23T06:07:25","slug":"reservation","status":"publish","type":"page","link":"https:\/\/www.maximus-resort.cz\/en\/reservation\/","title":{"rendered":"Online reservation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":102,"comment_status":"closed","ping_status":"closed","template":"page-bookolo.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3782","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.maximus-resort.cz\/en\/reservation\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hotel Brno Maximus Resort -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Online reservation - Hotel Brno Maximus Resort\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.maximus-resort.cz\/en\/reservation\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/10\/19c0cab6-2726-496d-a717-711e0fb87efb.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/10\/19c0cab6-2726-496d-a717-711e0fb87efb.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-03T13:29:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-23T06:07:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maximus.resort\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Online reservation - Hotel Brno Maximus Resort\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/10\/19c0cab6-2726-496d-a717-711e0fb87efb.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#listItem\",\"name\":\"Online reservation\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#listItem\",\"position\":2,\"name\":\"Online reservation\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/#organization\",\"name\":\"Maximus Resort, a.s.\",\"description\":\"D\\u00edky sv\\u00e9mu um\\u00edst\\u011bn\\u00ed a geniu loci je Maximus Resort v Brn\\u011b vyhled\\u00e1van\\u00fd nejen pro wellness pobyty, ale tak\\u00e9 pro svatby, rodinn\\u00e9 oslavy nebo jak\\u00e9koliv firemn\\u00ed akce. Pro\\u017eijte u n\\u00e1s kr\\u00e1sn\\u00e9 chv\\u00edle i vy. U\\u017eijte si \\u010dty\\u0159hv\\u011bzdi\\u010dkov\\u00e9 ubytov\\u00e1n\\u00ed, z\\u00e1\\u017eitkovou gastronomii i \\u0161pi\\u010dkov\\u00e9 wellness a SPA centrum, relaxa\\u010dn\\u00ed procedury v salonu kr\\u00e1sy nebo \\u0159adu sportovn\\u00edch aktivit.\",\"url\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/\",\"email\":\"rezervace@maximus-resort.cz\",\"telephone\":\"+420546221035\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.maximus-resort.cz\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/10ee15c5-d70a-446d-8717-07ec09da57e6.svg\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#organizationLogo\",\"width\":180,\"height\":50},\"image\":{\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/maximus.resort\",\"https:\\\/\\\/instagram.com\\\/maximusresortofficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maximus-resort-a-s-\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#webpage\",\"url\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/\",\"name\":\"Online reservation - Hotel Brno Maximus Resort\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/reservation\\\/#breadcrumblist\"},\"datePublished\":\"2024-12-03T14:29:29+01:00\",\"dateModified\":\"2025-10-23T08:07:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/\",\"name\":\"Hotel Brno Maximus Resort\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maximus-resort.cz\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Online reservation - Hotel Brno Maximus Resort","description":"","canonical_url":"https:\/\/www.maximus-resort.cz\/en\/reservation\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.maximus-resort.cz\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.maximus-resort.cz\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#listItem","name":"Online reservation"}},{"@type":"ListItem","@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#listItem","position":2,"name":"Online reservation","previousItem":{"@type":"ListItem","@id":"https:\/\/www.maximus-resort.cz\/en\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.maximus-resort.cz\/en\/#organization","name":"Maximus Resort, a.s.","description":"D\u00edky sv\u00e9mu um\u00edst\u011bn\u00ed a geniu loci je Maximus Resort v Brn\u011b vyhled\u00e1van\u00fd nejen pro wellness pobyty, ale tak\u00e9 pro svatby, rodinn\u00e9 oslavy nebo jak\u00e9koliv firemn\u00ed akce. Pro\u017eijte u n\u00e1s kr\u00e1sn\u00e9 chv\u00edle i vy. U\u017eijte si \u010dty\u0159hv\u011bzdi\u010dkov\u00e9 ubytov\u00e1n\u00ed, z\u00e1\u017eitkovou gastronomii i \u0161pi\u010dkov\u00e9 wellness a SPA centrum, relaxa\u010dn\u00ed procedury v salonu kr\u00e1sy nebo \u0159adu sportovn\u00edch aktivit.","url":"https:\/\/www.maximus-resort.cz\/en\/","email":"rezervace@maximus-resort.cz","telephone":"+420546221035","logo":{"@type":"ImageObject","url":"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/09\/10ee15c5-d70a-446d-8717-07ec09da57e6.svg","@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#organizationLogo","width":180,"height":50},"image":{"@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/maximus.resort","https:\/\/instagram.com\/maximusresortofficial","https:\/\/www.linkedin.com\/company\/maximus-resort-a-s-\/"]},{"@type":"WebPage","@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#webpage","url":"https:\/\/www.maximus-resort.cz\/en\/reservation\/","name":"Online reservation - Hotel Brno Maximus Resort","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.maximus-resort.cz\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.maximus-resort.cz\/en\/reservation\/#breadcrumblist"},"datePublished":"2024-12-03T14:29:29+01:00","dateModified":"2025-10-23T08:07:25+02:00"},{"@type":"WebSite","@id":"https:\/\/www.maximus-resort.cz\/en\/#website","url":"https:\/\/www.maximus-resort.cz\/en\/","name":"Hotel Brno Maximus Resort","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.maximus-resort.cz\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Hotel Brno Maximus Resort -","og:type":"article","og:title":"Online reservation - Hotel Brno Maximus Resort","og:url":"https:\/\/www.maximus-resort.cz\/en\/reservation\/","og:image":"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/10\/19c0cab6-2726-496d-a717-711e0fb87efb.png","og:image:secure_url":"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/10\/19c0cab6-2726-496d-a717-711e0fb87efb.png","og:image:width":1200,"og:image:height":675,"article:published_time":"2024-12-03T13:29:29+00:00","article:modified_time":"2025-10-23T06:07:25+00:00","article:publisher":"https:\/\/www.facebook.com\/maximus.resort","twitter:card":"summary_large_image","twitter:title":"Online reservation - Hotel Brno Maximus Resort","twitter:image":"https:\/\/www.maximus-resort.cz\/wp-content\/uploads\/2024\/10\/19c0cab6-2726-496d-a717-711e0fb87efb.png"},"aioseo_meta_data":{"post_id":"3782","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-10-21 13:52:15","updated":"2025-10-23 06:08:30","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.maximus-resort.cz\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOnline reservation\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.maximus-resort.cz\/en\/"},{"label":"Online reservation","link":"https:\/\/www.maximus-resort.cz\/en\/reservation\/"}],"_links":{"self":[{"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/pages\/3782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/comments?post=3782"}],"version-history":[{"count":2,"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/pages\/3782\/revisions"}],"predecessor-version":[{"id":4415,"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/pages\/3782\/revisions\/4415"}],"wp:attachment":[{"href":"https:\/\/www.maximus-resort.cz\/en\/wp-json\/wp\/v2\/media?parent=3782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}